{"id":9,"count":4,"description":"","link":"https:\/\/www.tischlerei-beelitz.com\/en\/category\/sicherheit-schutz\/","name":"Safety &amp; protection","slug":"sicherheit-schutz","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sicherheit &amp; Brandschutz \u2013 Informationen &amp; L\u00f6sungen<\/title>\n<meta name=\"description\" content=\"Entdecken Sie umfassende Inhalte zu Brandschutz, Sicherheit und Pr\u00e4vention \u2013 praxisnah erkl\u00e4rt f\u00fcr Handwerk, Betriebe und Baubranche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tischlerei-beelitz.com\/en\/category\/sicherheit-schutz\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sicherheit &amp; Brandschutz \u2013 Informationen &amp; L\u00f6sungen\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie umfassende Inhalte zu Brandschutz, Sicherheit und Pr\u00e4vention \u2013 praxisnah erkl\u00e4rt f\u00fcr Handwerk, Betriebe und Baubranche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tischlerei-beelitz.com\/en\/category\/sicherheit-schutz\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tischlerei-beelitz.com\/wp-content\/uploads\/2025\/07\/Medien-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.tischlerei-beelitz.com\/category\/sicherheit-schutz\/\",\"url\":\"https:\/\/www.tischlerei-beelitz.com\/category\/sicherheit-schutz\/\",\"name\":\"Sicherheit & Brandschutz \u2013 Informationen & L\u00f6sungen\",\"isPartOf\":{\"@id\":\"https:\/\/www.tischlerei-beelitz.com\/#website\"},\"description\":\"Entdecken Sie umfassende Inhalte zu Brandschutz, Sicherheit und Pr\u00e4vention \u2013 praxisnah erkl\u00e4rt f\u00fcr Handwerk, Betriebe und Baubranche.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tischlerei-beelitz.com\/category\/sicherheit-schutz\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tischlerei-beelitz.com\/category\/sicherheit-schutz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.tischlerei-beelitz.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sicherheit &amp; Schutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tischlerei-beelitz.com\/#website\",\"url\":\"https:\/\/www.tischlerei-beelitz.com\/\",\"name\":\"www.tischlerei-beelitz.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.tischlerei-beelitz.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tischlerei-beelitz.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tischlerei-beelitz.com\/#organization\",\"name\":\"MB Brandschutztischlerei Beelitz GmbH\",\"url\":\"https:\/\/www.tischlerei-beelitz.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.tischlerei-beelitz.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tischlerei-beelitz.com\/wp-content\/uploads\/2025\/05\/logo-brandschutz-tischlerei-beelitz.png\",\"contentUrl\":\"https:\/\/www.tischlerei-beelitz.com\/wp-content\/uploads\/2025\/05\/logo-brandschutz-tischlerei-beelitz.png\",\"width\":300,\"height\":263,\"caption\":\"MB Brandschutztischlerei Beelitz GmbH\"},\"image\":{\"@id\":\"https:\/\/www.tischlerei-beelitz.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/mbbrandschutztischlerei\/\",\"https:\/\/www.instagram.com\/mb_brandschutztischlerei\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sicherheit & Brandschutz \u2013 Informationen & L\u00f6sungen","description":"Discover comprehensive content on fire protection, safety and prevention - explained in a practical way for tradespeople, businesses and the construction industry.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tischlerei-beelitz.com\/en\/category\/sicherheit-schutz\/","og_locale":"en_GB","og_type":"article","og_title":"Sicherheit & Brandschutz \u2013 Informationen & L\u00f6sungen","og_description":"Entdecken Sie umfassende Inhalte zu Brandschutz, Sicherheit und Pr\u00e4vention \u2013 praxisnah erkl\u00e4rt f\u00fcr Handwerk, Betriebe und Baubranche.","og_url":"https:\/\/www.tischlerei-beelitz.com\/en\/category\/sicherheit-schutz\/","og_image":[{"width":500,"height":500,"url":"https:\/\/www.tischlerei-beelitz.com\/wp-content\/uploads\/2025\/07\/Medien-5.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.tischlerei-beelitz.com\/category\/sicherheit-schutz\/","url":"https:\/\/www.tischlerei-beelitz.com\/category\/sicherheit-schutz\/","name":"Safety &amp; fire protection - Information &amp; solutions","isPartOf":{"@id":"https:\/\/www.tischlerei-beelitz.com\/#website"},"description":"Discover comprehensive content on fire protection, safety and prevention - explained in a practical way for tradespeople, businesses and the construction industry.","breadcrumb":{"@id":"https:\/\/www.tischlerei-beelitz.com\/category\/sicherheit-schutz\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tischlerei-beelitz.com\/category\/sicherheit-schutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.tischlerei-beelitz.com\/"},{"@type":"ListItem","position":2,"name":"Sicherheit &amp; Schutz"}]},{"@type":"WebSite","@id":"https:\/\/www.tischlerei-beelitz.com\/#website","url":"https:\/\/www.tischlerei-beelitz.com\/","name":"www.tischlerei-beelitz.com","description":"","publisher":{"@id":"https:\/\/www.tischlerei-beelitz.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tischlerei-beelitz.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.tischlerei-beelitz.com\/#organization","name":"MB Brandschutztischlerei Beelitz GmbH","url":"https:\/\/www.tischlerei-beelitz.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.tischlerei-beelitz.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.tischlerei-beelitz.com\/wp-content\/uploads\/2025\/05\/logo-brandschutz-tischlerei-beelitz.png","contentUrl":"https:\/\/www.tischlerei-beelitz.com\/wp-content\/uploads\/2025\/05\/logo-brandschutz-tischlerei-beelitz.png","width":300,"height":263,"caption":"MB Brandschutztischlerei Beelitz GmbH"},"image":{"@id":"https:\/\/www.tischlerei-beelitz.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mbbrandschutztischlerei\/","https:\/\/www.instagram.com\/mb_brandschutztischlerei\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.tischlerei-beelitz.com\/en\/wp-json\/wp\/v2\/categories\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tischlerei-beelitz.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.tischlerei-beelitz.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.tischlerei-beelitz.com\/en\/wp-json\/wp\/v2\/posts?categories=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}